{"id":7257,"date":"2014-05-01T11:02:13","date_gmt":"2014-05-01T09:02:13","guid":{"rendered":"https:\/\/spacetux.org\/cpamoa\/?p=7257"},"modified":"2014-05-01T11:03:46","modified_gmt":"2014-05-01T09:03:46","slug":"l-207-dautres-examens-soyouz-reussis-notre-equipage","status":"publish","type":"post","link":"https:\/\/spacetux.org\/cpamoa\/2014\/05\/l-207-dautres-examens-soyouz-reussis-notre-equipage\/","title":{"rendered":"L-207 : D&rsquo;autres examens Soyouz r\u00e9ussis pour notre \u00e9quipage !"},"content":{"rendered":"<p><strong>L-207 : Jeudi 1er mai 2014<\/strong><\/p>\n<p>Terry, Anton et moi avons mis quelques examens de plus derri\u00e8re nous ces derniers jours.<\/p>\n<p>Mardi nous avons r\u00e9ussi nos examens th\u00e9oriques sur le programme de vol &#8211; \u00e0 la fois du Soyouz et du segment russe. Celui du Soyouz \u00e9tait particuli\u00e8rement\u00a0tr\u00e8s int\u00e9ressant car ce sont toujours des occasions d&rsquo;apprendre des petits d\u00e9tails des personne qui contr\u00f4lent le vol depuis le Contr\u00f4le de Mission de Moscou.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2014\/05\/L-207-Samantha-dans-le-module-orbital-du-Soyouz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7258\" src=\"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2014\/05\/L-207-Samantha-dans-le-module-orbital-du-Soyouz.jpg\" alt=\"Samantha dans le module orbital du Soyouz\" width=\"600\" height=\"450\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Hier nous avons pass\u00e9\u00a0notre examen concernant\u00a0les rendez-vous manuels &#8211; c&rsquo;est l\u00e0 qu&rsquo;Anton\u00a0doit montrer\u00a0ses comp\u00e9tences pour piloter une approche manuelle depuis environ 2-3km de l&rsquo;ISS jusqu&rsquo;\u00e0\u00a0une position de maintien \u00e0 50-100 m\u00e8tres du port d&rsquo;amarrage, tandis que je vais dans le module orbital et que j&rsquo;utilise un t\u00e9l\u00e9m\u00e8tre laser \u00e0 travers une fen\u00eatre orient\u00e9e vers\u00a0l&rsquo;avant pour lui donner les mesures de distance et de vitesse.<\/p>\n<p>Cette situation est pr\u00e9vue dans notre profil de deux jours entre le lancement et l&rsquo;amarrage, pas dans le profil nominal actuel de six heures. C&rsquo;est parce que dans le profil plus court il n&rsquo;y a pas de temps pour mettre en place\u00a0le t\u00e9l\u00e9m\u00e8tre laser dans le module orbital avant le d\u00e9but des allumages de rendez-vous du moteur. Si une panne venait \u00e0 se produire quand nous sommes encore \u00e0 quelques kilom\u00e8tres de la Station, nous interromprions l&rsquo;approche et nous chercherions \u00e0 comprendre le probl\u00e8me avec les \u00e9quipes au sol.<\/p>\n<p>Dans le profil de rendez-vous sur deux jours, cependant, apr\u00e8s les deux premi\u00e8res man\u0153uvres d&rsquo;\u00e9l\u00e9vation de l&rsquo;orbite nous faisons une pause, allons dans le module orbital et avons le temps d&rsquo;installer le t\u00e9l\u00e9m\u00e8tre laser de sorte qu&rsquo;il est pr\u00eat deux jours plus tard lorsque nous effectuons\u00a0vraiment notre approche vers l&rsquo;ISS.<\/p>\n<p>Aujourd&rsquo;hui c&rsquo;est une une grande f\u00eate ici en Russie, comme dans beaucoup d&rsquo;endroits dans le monde. Si vous le c\u00e9l\u00e9brez, Joyeux 1er Mai \u00e0 vous.<\/p>\n<p>Ici \u00e0 Star City nous sommes en cong\u00e9s jusqu&rsquo;\u00e0 lundi, mais avec la grosse journ\u00e9e d&rsquo;examen Soyouz qui vient\u00a0mardi prochain, je vais certainement\u00a0passer beaucoup de temps \u00e0 \u00e9tudier.<\/p>\n<pre><em style=\"font-weight: inherit;\">Cette note est la suite d\u2019une longue s\u00e9rie de notes de Samantha Cristoforetti qui a entrepris l\u2019\u00e9criture d\u2019un journal de bord quotidien qui la m\u00e8nera au jour de son lancement, pour le moment pr\u00e9vu le 24 novembre 2014.<\/em><\/pre>\n<pre><em style=\"font-weight: inherit;\">La version anglaise (originale) peut \u00eatre consult\u00e9e sur\u00a0<a style=\"font-weight: inherit; font-style: inherit; color: #0088ff;\" title=\"Article en anglais sur le compte G+ de Samantha\" href=\"https:\/\/plus.google.com\/u\/0\/+SamanthaCristoforetti\/posts\/PqVBBJfGcRD\" target=\"_blank\">son compte Google+<\/a>\u00a0et la traduction italienne sur le site\u00a0<a style=\"font-weight: inherit; font-style: inherit; color: #0088ff;\" title=\"Article en italien sur le site AstronautiNEWS\" href=\"http:\/\/www.astronautinews.it\/tag\/logbook\/\" target=\"_blank\">AstronautiNEWS<\/a>. Toutes les photos post\u00e9es sont sa propri\u00e9t\u00e9 et proviennent de son journal de bord sur son compte Google+.<\/em><\/pre>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L-207 : Jeudi 1er mai 2014 Terry, Anton et moi avons mis quelques examens de plus derri\u00e8re nous ces derniers jours. Mardi nous avons r\u00e9ussi nos examens th\u00e9oriques sur le programme de vol &#8211; \u00e0 la fois du Soyouz et du segment russe. Celui du Soyouz \u00e9tait particuli\u00e8rement\u00a0tr\u00e8s int\u00e9ressant car ce sont toujours des occasions d&rsquo;apprendre des petits d\u00e9tails des personne qui contr\u00f4lent le vol depuis le Contr\u00f4le de Mission de Moscou. &nbsp; &nbsp; Hier nous avons pass\u00e9\u00a0notre examen concernant\u00a0les<\/p>\n","protected":false},"author":1,"featured_media":7258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195],"tags":[227,354,359,523,537,563],"class_list":["post-7257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logbook-samantha","tag-approche","tag-examens","tag-expedition-42","tag-rendez-vous","tag-samantha-cristoforetti","tag-soyouz"],"jetpack_featured_media_url":"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2014\/05\/L-207-Samantha-dans-le-module-orbital-du-Soyouz.jpg","jetpack_shortlink":"https:\/\/wp.me\/p4aZXT-1T3","_links":{"self":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/comments?post=7257"}],"version-history":[{"count":4,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7257\/revisions"}],"predecessor-version":[{"id":7262,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7257\/revisions\/7262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media\/7258"}],"wp:attachment":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media?parent=7257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/categories?post=7257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/tags?post=7257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}