{"id":7303,"date":"2014-05-04T11:52:01","date_gmt":"2014-05-04T09:52:01","guid":{"rendered":"https:\/\/spacetux.org\/cpamoa\/?p=7303"},"modified":"2014-05-04T11:54:36","modified_gmt":"2014-05-04T09:54:36","slug":"l-204-dincroyables-amis","status":"publish","type":"post","link":"https:\/\/spacetux.org\/cpamoa\/2014\/05\/l-204-dincroyables-amis\/","title":{"rendered":"L-204 : D&rsquo;incroyables amis !"},"content":{"rendered":"<p><strong>L-204 : Dimanche 4 mai 2014<\/strong><\/p>\n<p>Faisant une pause dans la pr\u00e9paration de mon gros examen de la semaine prochaine, j&rsquo;aimerais partager avec vous quelque chose pour laquelle je suis vraiment enthousiaste : le partenariat entre ma mission Futura et l&rsquo;\u00e9quipe WeFly!.<\/p>\n<p>WeFly! est une \u00e9quipe de voltige vraiment sp\u00e9ciale, qui vole sur des machines ultra-l\u00e9g\u00e8res : deux des trois pilotes ont un handicap, ce qui les oblige \u00e0 utiliser un fauteuil roulant pendant la journ\u00e9e et des commandes modifi\u00e9es dans le cockpit qui leur permettent un contr\u00f4le total de l&rsquo;avion en n&rsquo;utilisant que les mains.<\/p>\n<p>J&rsquo;ai eu le privil\u00e8ge de rencontrer Alessandro, Marco et Erich il y a environ sept ans. Dans cette courte vid\u00e9o je raconte cette histoire :<\/p>\n<p>&nbsp;<\/p>\n<p><em>Samantha Cristoforetti and WeFly Team\u00a0together for the disabled people :<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/R870bqIg9Xg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>WeFly avec Futura : Oser voler !<br \/>\n&nbsp;<br \/>\n<p class=\"jetpack-slideshow-noscript robots-nocontent\">Ce diaporama n\u00e9cessite JavaScript.<\/p><div id=\"gallery-7303-1-slideshow\" class=\"jetpack-slideshow-window jetpack-slideshow jetpack-slideshow-black\" data-trans=\"fade\" data-autostart=\"1\" data-gallery=\"[{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura1.jpg&quot;,&quot;id&quot;:&quot;7304&quot;,&quot;title&quot;:&quot;WeFly with Futura1&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura2.jpg&quot;,&quot;id&quot;:&quot;7305&quot;,&quot;title&quot;:&quot;WeFly with Futura2&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura3.jpg&quot;,&quot;id&quot;:&quot;7306&quot;,&quot;title&quot;:&quot;WeFly with Futura3&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura4.jpg&quot;,&quot;id&quot;:&quot;7307&quot;,&quot;title&quot;:&quot;WeFly with Futura4&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura5.jpg&quot;,&quot;id&quot;:&quot;7308&quot;,&quot;title&quot;:&quot;WeFly with Futura5&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;},{&quot;src&quot;:&quot;https:\\\/\\\/spacetux.org\\\/cpamoa\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/WeFly-with-Futura6.jpg&quot;,&quot;id&quot;:&quot;7309&quot;,&quot;title&quot;:&quot;WeFly with Futura6&quot;,&quot;alt&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;itemprop&quot;:&quot;image&quot;}]\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><\/div><\/p>\n<p>&nbsp;<\/p>\n<pre><em style=\"font-weight: inherit;\">Cette note est la suite d\u2019une longue s\u00e9rie de notes de Samantha Cristoforetti qui a entrepris l\u2019\u00e9criture d\u2019un journal de bord quotidien qui la m\u00e8nera au jour de son lancement, pour le moment pr\u00e9vu le 24 novembre 2014.<\/em><\/pre>\n<pre><em style=\"font-weight: inherit;\">La version anglaise (originale) peut \u00eatre consult\u00e9e sur\u00a0<a style=\"font-weight: inherit; font-style: inherit; color: #0088ff;\" title=\"Article en anglais sur le compte G+ de Samantha\" href=\"https:\/\/plus.google.com\/+SamanthaCristoforetti\/posts\/gz4JwqPjKLx\" target=\"_blank\">son compte Google+<\/a>\u00a0et la traduction italienne sur le site\u00a0<a style=\"font-weight: inherit; font-style: inherit; color: #0088ff;\" title=\"Article en italien sur le site AstronautiNEWS\" href=\"https:\/\/plus.google.com\/+SamanthaCristoforetti\/posts\/gz4JwqPjKLx\" target=\"_blank\">AstronautiNEWS<\/a>. Toutes les photos post\u00e9es sont sa propri\u00e9t\u00e9 et proviennent de son journal de bord sur son compte Google+.<\/em><\/pre>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L-204 : Dimanche 4 mai 2014 Faisant une pause dans la pr\u00e9paration de mon gros examen de la semaine prochaine, j&rsquo;aimerais partager avec vous quelque chose pour laquelle je suis vraiment enthousiaste : le partenariat entre ma mission Futura et l&rsquo;\u00e9quipe WeFly!. WeFly! est une \u00e9quipe de voltige vraiment sp\u00e9ciale, qui vole sur des machines ultra-l\u00e9g\u00e8res : deux des trois pilotes ont un handicap, ce qui les oblige \u00e0 utiliser un fauteuil roulant pendant la journ\u00e9e et des commandes modifi\u00e9es<\/p>\n","protected":false},"author":1,"featured_media":7304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195],"tags":[537,754],"class_list":["post-7303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logbook-samantha","tag-samantha-cristoforetti","tag-wefly"],"jetpack_featured_media_url":"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2014\/05\/WeFly-with-Futura1.jpg","jetpack_shortlink":"https:\/\/wp.me\/p4aZXT-1TN","_links":{"self":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/comments?post=7303"}],"version-history":[{"count":6,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7303\/revisions"}],"predecessor-version":[{"id":7315,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/7303\/revisions\/7315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media\/7304"}],"wp:attachment":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media?parent=7303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/categories?post=7303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/tags?post=7303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}