{"id":8093,"date":"2015-01-14T17:17:37","date_gmt":"2015-01-14T16:17:37","guid":{"rendered":"https:\/\/spacetux.org\/cpamoa\/?p=8093"},"modified":"2015-01-14T17:17:37","modified_gmt":"2015-01-14T16:17:37","slug":"l50-lodeur-de-lespace-une-dominance-de-brule-avec-une-touche-de-pourri","status":"publish","type":"post","link":"https:\/\/spacetux.org\/cpamoa\/2015\/01\/l50-lodeur-de-lespace-une-dominance-de-brule-avec-une-touche-de-pourri\/","title":{"rendered":"L+50 : L&rsquo;odeur de l&rsquo;espace ? Une dominance de \u00ab\u00a0br\u00fbl\u00e9\u00a0\u00bb avec une touche de \u00ab\u00a0pourri\u00a0\u00bb"},"content":{"rendered":"<p><strong>L+50 : Lundi 12 Janvier 2015<\/strong><\/p>\n<p><em>(\u00e9crit par Samantha le Mardi 13 Janvier)<\/em><\/p>\n<p>Mon 50\u00e8me jour dans l&rsquo;espace et certainement un grand jour ici dans l&rsquo;ISS hier &#8211; puisque je suis s\u00fbre que vous l&rsquo;avez entendu, le Dragon est arriv\u00e9 ! Nous avons maintenant une nouvelle pi\u00e8ce\u00a0attach\u00e9e sur le cot\u00e9 \u00ab\u00a0Terre\u00a0\u00bb du Node 2, juste \u00e0 cot\u00e9 de nos quartiers d&rsquo;\u00e9quipage :\u00a0depuis mon arriv\u00e9e dans l&rsquo;ISS, il y avait \u00e0 cet endroit-l\u00e0 une trappe qui menait vers le vide, maintenant je peux prendre le virage\u00a0et plonger dans le Dragon. Notre maison de l&rsquo;espace vient de s&rsquo;agrandir\u00a0!<\/p>\n<p>L&rsquo;approche et la capture se sont d\u00e9roul\u00e9es\u00a0le matin, et tout du moins\u00a0de notre point de vue, tout s&rsquo;est vraiment bien pass\u00e9. C&rsquo;\u00e9tait tr\u00e8s touchant de voir ce v\u00e9hicule approcher de l&rsquo;ISS et discerner de plus en plus de d\u00e9tails au fur et \u00e0 mesure qu&rsquo;il se rapprochait, un messager venant de la Terre apportant du ravitaillement aux seuls six humains\u00a0actuellement non pr\u00e9sents sur la plan\u00e8te.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8095\" src=\"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola.jpg\" alt=\"L+50 Samantha Cristoforetti et Butch Wilmore sur le point de capturer le Dragon depuis la Cupola\" width=\"600\" height=\"437\" srcset=\"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola.jpg 1600w, https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola-300x218.jpg 300w, https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola-1024x746.jpg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>J&rsquo;\u00e9tais impressionn\u00e9e par sa stabilit\u00e9 lorsqu&rsquo;il est arriv\u00e9 par en-dessous : on pouvait \u00e0 peine remarquer qu&rsquo;il contr\u00f4lait sa position et son orientation. Au moment o\u00f9 il s&rsquo;est arr\u00eat\u00e9 au dernier point d&rsquo;attente \u00e0 30 m\u00e8tres, il donnait l&rsquo;impression d&rsquo;\u00eatre d\u00e9j\u00e0 si proche que je ne pouvais pas croire qu&rsquo;il s&rsquo;approcherait encore de 20 m\u00e8tres avant que nous puissions l&rsquo;attraper, mais bien s\u00fbr, l\u00e0-dehors nous n&rsquo;avons pas beaucoup de r\u00e9f\u00e9rences pour jauger la distance. Il est arriv\u00e9 au point de capture, \u00e0 10 m\u00e8tres de distance, pendant la nuit orbitale, avec les lumi\u00e8res vertes et rouges sur les cot\u00e9s se refl\u00e9tant magnifiquement sur les panneaux solaires. Juste apr\u00e8s le lever du soleil, nous avons eu le \u00ab\u00a0GO pour la capture\u00a0\u00bb de Houston et Butch a man\u0153uvr\u00e9 doucement le bras robotique sur la broche de capture et a tir\u00e9 sur la g\u00e2chette pour lancer la s\u00e9quence de capture. j&rsquo;avais toutes les cartes aide-m\u00e9moire de dysfonctionnement pr\u00eates, mais heureusement il n&rsquo;y en a pas eu besoin. Tout s&rsquo;est parfaitement bien pass\u00e9 !<\/p>\n<p>Apr\u00e8s cela nous avons s\u00e9curis\u00e9 le bras et le sol a pris le contr\u00f4le pour man\u0153uvrer le Dragon vers sa position d&rsquo;amarrage sur le port du Node 2 situ\u00e9 cot\u00e9 Terre. Une fois que les boulons qui cr\u00e9ent une liaison m\u00e9canique solide ont \u00e9t\u00e9 serr\u00e9s, j&rsquo;ai re\u00e7u le feu vert pour contr\u00f4ler l&rsquo;\u00e9tanch\u00e9it\u00e9 du vestibule : si vous vous demandez ce que c&rsquo;est, disons que c&rsquo;est l&rsquo;espace entre les portes.<\/p>\n<p>Nous avons une trappe de notre cot\u00e9, le Dragon a une trappe de son cot\u00e9 : lorsque les trappes sont ouvertes, nous devons avoir un \u00ab\u00a0couloir\u00a0\u00bb entre les deux qui soit \u00e9tanche \u00e0 la pression pour nous permettre de le traverser ; c&rsquo;est appel\u00e9 le vestibule. Juste apr\u00e8s l&rsquo;amarrage, le vestibule est sous vide : si vous y pensez, il est \u00e0 l&rsquo;ext\u00e9rieur de la trappe de notre cot\u00e9 et \u00e0 l&rsquo;ext\u00e9rieur de la trappe du cot\u00e9 Dragon. Avant d&rsquo;\u00e9galiser la pression et d&rsquo;ouvrir la trappe, il est important de s&rsquo;assurer que le vestibule ne fuit pas. Pour ce faire, j&rsquo;ai ouvert un patch entre le vestibule et l&rsquo;ISS et j&rsquo;ai pressuris\u00e9 le vestibule \u00e0 260mmHg (environ\u00a00.34 atmosph\u00e8re, NdlT), puis j&rsquo;ai v\u00e9rifi\u00e9 que la pression restait stable pendant 20 minutes. A ce moment-l\u00e0, j&rsquo;ai enti\u00e8rement \u00e9galis\u00e9 la pression et Terry et Butch ont pris le relais pour ouvrir la trappe et reconfigurer le vestibule pour\u00a0la p\u00e9riode o\u00f9 le Dragon restera dans l&rsquo;ISS.<\/p>\n<p>A un moment donn\u00e9, une fois que la trappe de notre cot\u00e9 a \u00e9t\u00e9 ouverte, Terry m&rsquo;a invit\u00e9e \u00e0 sentir \u00ab\u00a0l&rsquo;odeur de l&rsquo;espace\u00a0\u00bb dans le vestibule. C&rsquo;est un peu une blague, bien s\u00fbr, l&rsquo;espace en lui-m\u00eame n&rsquo;a pas d&rsquo;odeur. Mais c&rsquo;est apparemment l&rsquo;odeur caract\u00e9ristique du mat\u00e9riel qui a \u00e9t\u00e9 expos\u00e9 au vide. Pas une odeur agr\u00e9able, je vous le dis : je dirais que c&rsquo;est une dominance de\u00a0\u00ab\u00a0br\u00fbl\u00e9\u00a0\u00bb avec une touche de \u00ab\u00a0pourri\u00a0\u00bb. Mais bon, si cela signifie qu&rsquo;un vaisseau spatial est en visite, je l&rsquo;accepterai.<\/p>\n<p>&nbsp;<\/p>\n<pre><em>Cette note est la suite d\u2019une longue s\u00e9rie de notes de Samantha Cristoforetti, astronaute italienne de l'ESA, qui a entrepris l\u2019\u00e9criture d\u2019un journal de bord quotidien relatant son entra\u00eenement pour sa mission spatiale \u00e0 bord de l'ISS. Samantha s'est envol\u00e9e de Ba\u00efkonour \u00e0 bord d'une fus\u00e9e Soyouz le 23 novembre 2014.<\/em><\/pre>\n<pre><em>La version anglaise (originale) peut \u00eatre consult\u00e9e sur <a title=\"Article en anglais sur le compte G+ de Samantha\" href=\"https:\/\/plus.google.com\/u\/0\/+SamanthaCristoforetti\/posts\/UDf7eYLGC9y\" target=\"_blank\">son compte Google+<\/a> et la traduction italienne sur le site <a title=\"Article en italien sur le site AstronautiNEWS\" href=\"http:\/\/www.astronautinews.it\/2015\/01\/14\/l50-lodore-dello-spazio\/\" target=\"_blank\">AstronautiNEWS<\/a>. Toutes les photos post\u00e9es proviennent de son journal de bord sur son compte Google+.<\/em><\/pre>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L+50 : Lundi 12 Janvier 2015 (\u00e9crit par Samantha le Mardi 13 Janvier) Mon 50\u00e8me jour dans l&rsquo;espace et certainement un grand jour ici dans l&rsquo;ISS hier &#8211; puisque je suis s\u00fbre que vous l&rsquo;avez entendu, le Dragon est arriv\u00e9 ! Nous avons maintenant une nouvelle pi\u00e8ce\u00a0attach\u00e9e sur le cot\u00e9 \u00ab\u00a0Terre\u00a0\u00bb du Node 2, juste \u00e0 cot\u00e9 de nos quartiers d&rsquo;\u00e9quipage :\u00a0depuis mon arriv\u00e9e dans l&rsquo;ISS, il y avait \u00e0 cet endroit-l\u00e0 une trappe qui menait vers le vide, maintenant<\/p>\n","protected":false},"author":1,"featured_media":8095,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[195],"tags":[217,271,330,359,682,537],"class_list":["post-8093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logbook-samantha","tag-amarrage","tag-capture","tag-dragon","tag-expedition-42","tag-mission-futura","tag-samantha-cristoforetti"],"jetpack_featured_media_url":"https:\/\/spacetux.org\/cpamoa\/wp-content\/uploads\/2015\/01\/L-50-Samantha-Cristoforetti-et-Butch-Wilmore-sur-le-point-de-capturer-le-Dragon-depuis-la-Cupola.jpg","jetpack_shortlink":"https:\/\/wp.me\/p4aZXT-26x","_links":{"self":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/8093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/comments?post=8093"}],"version-history":[{"count":2,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/8093\/revisions"}],"predecessor-version":[{"id":8096,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/posts\/8093\/revisions\/8096"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media\/8095"}],"wp:attachment":[{"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/media?parent=8093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/categories?post=8093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spacetux.org\/cpamoa\/wp-json\/wp\/v2\/tags?post=8093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}